{"id":2510,"date":"2022-08-04T07:20:38","date_gmt":"2022-08-04T07:20:38","guid":{"rendered":"https:\/\/practicalhealthpsychology.com\/?p=2510"},"modified":"2025-11-04T14:01:36","modified_gmt":"2025-11-04T14:01:36","slug":"make-or-break-the-importance-of-breaks-in-healthcare","status":"publish","type":"post","link":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/","title":{"rendered":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Di Julia Allan, Aberdeen University, Scozia<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La vita moderna \u00e8 frenetica. Viviamo in un mondo digitale sempre pi\u00f9 \u201cconnesso\u201d, in cui i momenti di reale stacco dal lavoro sono rari. Molte persone fanno regolarmente orari prolungati, e questo vale in particolar modo per gli operatori sanitari occupati in prima linea nei servizi di cura. Nel contesto sanitario, gli orari di lavoro e le richieste sono solitamente impegnativi, i turni superano abitualmente le 8 ore di una \u201cnormale\u201d giornata lavorativa, e le richieste sono per loro natura senza sosta. Se il flusso di pazienti che richiedono cure urgenti \u00e8 continuativo, i professionisti sanitari sono obbligati a fornirle, a prescindere da quanto siano stati impegnati o da quante ore stiano lavorando. A causa di queste richieste elevate, rinunciare alle pause \u00e8 qualcosa di estremamente comune nei contesti sanitari \u2013 ad esempio, \u00e8 stato dimostrato che <\/span><a href=\"https:\/\/journals.sagepub.com\/doi\/pdf\/10.1177\/216507991005801106\"><span style=\"font-weight: 400;\">1 infermiere su 10 non fa mai una vera e propria pausa, ed 1 su 3 non fa o fa raramente una pausa pranzo durante i turni. <\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Le pause mancate comportano una serie di conseguenze negative \u2013 dal disagio pratico derivante dal non avere il tempo di andare in bagno e <\/span><a href=\"https:\/\/opus.lib.uts.edu.au\/bitstream\/10453\/113597\/4\/Barriers%20and%20facilitators%20to%20healthy%20eating%20for%20nurses%20in%20the%20workplace%202016.pdf\"><span style=\"font-weight: 400;\">dalla mancata possibilit\u00e0 di mangiare in modo sano<\/span><\/a><span style=\"font-weight: 400;\">, ai sentimenti di <\/span><a href=\"https:\/\/bmcnurs.biomedcentral.com\/articles\/10.1186\/s12912-020-00481-3\"><span style=\"font-weight: 400;\">demoralizzazione e insoddisfazione<\/span><\/a><span style=\"font-weight: 400;\"> e ai cambiamenti cognitivi che i periodi di lavoro prolungati senza intervalli adeguati possono provocare.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">I cambiamenti cognitivi che avvengono quando si lavora per periodi prolungati senza pause sono uno dei principali argomenti a sostegno del fare intervalli regolari. Tutti conosciamo la sensazione di sentirsi stanchi e esauriti al termine di una lunga giornata lavorativa, quando siamo in difficolt\u00e0 nel prendere delle decisioni o non riusciamo a concentrarci sul compito che abbiamo davanti. Questo calo nella performance cognitiva \u00e8 assolutamente naturale, ed \u00e8 la dimostrazione del fatto che la cognizione umana semplicemente non \u00e8 progettata per concentrarsi in modo continuativo su uno stesso compito per lunghi periodi di tempo. In realt\u00e0, in termini cognitivi, l\u2019affaticamento \u00e8 un <\/span><a href=\"https:\/\/books.google.co.uk\/books?id=oQBeAwAAQBAJ&amp;dq=robert+hockey+mental+fatigue&amp;lr=\"><span style=\"font-weight: 400;\">segnale adattivo<\/span><\/a><span style=\"font-weight: 400;\"> \u2013 un segno che abbiamo trascorso troppo tempo impegnati in quella mansione e abbiamo bisogno di prenderci una pausa prima di iniziare a commettere errori.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Gli effetti negativi del lavoro continuativo senza intervalli erano gi\u00e0 chiari oltre un secolo fa. In uno degli esempi pi\u00f9 eroici, <\/span><a href=\"https:\/\/www.apadivisions.org\/division-35\/about\/heritage\/tsuruko-haraguchi-biography\"><span style=\"font-weight: 400;\">Tsuro Arai<\/span><\/a><span style=\"font-weight: 400;\">, la prima donna giapponese ad aver ottenuto un dottorato, si costrinse a completare una mansione lavorativa che richiedeva concentrazione (risolvere problemi con moltiplicazioni complesse) continuativamente per 12 ore per pi\u00f9 giorni consecutivi senza riposare. Com\u2019era prevedibile, col passare delle ore impegnata in quel compito, la sua performance divent\u00f2 progressivamente pi\u00f9 lenta e meno accurata, dimostrando per la prima volta empiricamente che una performance cognitiva ottimale non pu\u00f2 essere mantenuta per periodi di tempo che superano le 12 ore senza fare una pausa. Nonostante ci\u00f2, i professionisti sanitari di oggi trascorrono spesso periodi di tempo di tale durata senza adeguati intervalli per riposare. Un <\/span><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/15318582\/\"><span style=\"font-weight: 400;\">importante studio che ha coinvolto circa 400 infermieri su oltre 5000 turni<\/span><\/a><span style=\"font-weight: 400;\"> ha dimostrato che, in linea con i risultati dell\u2019esperimento di Arai, gli infermieri che lavoravano oltre 12 ore consecutive (circa il 40% dei turni analizzati nel campione), commettevano un quantitativo di errori significativamente maggiore.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Oltre agli errori collegati ai cali di memoria e attenzione, vi \u00e8 una crescente mole di evidenze che suggeriscono che la capacit\u00e0 di prendere decisioni si modifica in modo prevedibile durante lunghi periodi di lavoro \u2013 un fenomeno conosciuto come \u201caffaticamento decisionale [<\/span><i><span style=\"font-weight: 400;\">decision fatigue<\/span><\/i><span style=\"font-weight: 400;\">]\u201d. Nel momento in cui le persone prendono molte decisioni consecutive senza mai fermarsi, cominciano progressivamente a propendere per decisioni che in qualche modo risultano cognitivamente pi\u00f9 facili (ad esempio, procedere con l\u2019opzione standard, delegare ad altri la decisione, o usare il buon senso o scorciatoie). In ambito sanitario, vi sono chiare evidenze di questo fenomeno durante i turni di lavoro. Ad esempio<\/span><a href=\"https:\/\/jamanetwork.com\/journals\/jamainternalmedicine\/fullarticle\/1910546\"><span style=\"font-weight: 400;\">, i medici di medicina generale sono pi\u00f9 propensi a prescrivere antibiotici<\/span><\/a><span style=\"font-weight: 400;\"> non necessari durante l\u2019ultima parte del ricevimento ambulatoriale, e <\/span><a href=\"https:\/\/psycnet.apa.org\/record\/2019-15022-005\"><span style=\"font-weight: 400;\">gli infermieri tendono con pi\u00f9 frequenza a inviare i pazienti ad altri professionisti sanitari<\/span><\/a><span style=\"font-weight: 400;\"> all\u2019aumentare del tempo trascorso dall\u2019ultima pausa. Quest\u2019ultimo esempio solleva delle questioni chiave. Cognitivamente, il problema non \u00e8 rappresentato dalla mole di lavoro complessivo, ma la quantit\u00e0 di lavoro svolta <\/span><i><span style=\"font-weight: 400;\">senza intervalli.<\/span><\/i><span style=\"font-weight: 400;\"> In altre parole, l\u2019elemento critico per mantenere un funzionamento cognitivo ottimale nel tempo, \u00e8 la frequenza e la presenza (o assenza) di pause durante l\u2019orario lavorativo, piuttosto che il carico di lavoro complessivo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Garantire al personale sanitario delle pause di riposo all\u2019interno di un servizio sanitario affollato \u00e8 pi\u00f9 facile a dirsi che a farsi. Ma in questo caso, le evidenze parlano chiaro: qualunque pausa \u00e8 meglio di niente e bisognerebbe considerare le pause regolari come una parte della giornata lavorativa essenziale e non negoziabile. Anche quando non c\u2019\u00e8 tempo per fare una vera e propria pausa, le evidenze sottolineano come prendersi almeno un paio di minuti per distrarsi dal proprio compito, distendere i muscoli e respirare profondamente apporti benefici. Sembra che le \u201c<\/span><a href=\"https:\/\/www.bbc.com\/worklife\/article\/20190312-the-tiny-breaks-that-ease-your-body-and-reboot-your-brain\"><span style=\"font-weight: 400;\">micropause<\/span><\/a><span style=\"font-weight: 400;\">\u201d, pause di pochi minuti, siano sufficienti, nel corso di attivit\u00e0 impegnative, per mitigare almeno in parte gli effetti negativi di lunghi periodi di lavoro ininterrotto. Gli studi mostrano, ad esempio, che i chirurghi che fanno brevi micropause regolarmente durante le operazioni (dai 90 secondi ai 5 minuti di durata), riportano migliori <\/span><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/28059962\/\"><span style=\"font-weight: 400;\">performance fisiche e mentali<\/span><\/a><span style=\"font-weight: 400;\">, <\/span><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/20835716\/\"><span style=\"font-weight: 400;\">minor stress e meno eventi inaspettati durante le operazioni chirurgiche<\/span><\/a><span style=\"font-weight: 400;\">. \u00c8 importante sottolineare che le operazioni in cui sono stati inserite queste micropause hanno avuto durate non superiori a quelle delle operazioni standard, cosa che suggerisce come le pause si \u201cammortizzino autonomamente\u201d, controbilanciando il calo di velocit\u00e0 ed efficienza dovuto al passare del tempo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Riassumendo, le pause sono una parte essenziale della giornata lavorativa per i lavoratori della sanit\u00e0 (e di altri settori!).\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Raccomandazioni pratiche:<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li aria-level=\"1\"><b>Date priorit\u00e0 alle pause <span style=\"font-weight: 400;\">\u2013 \u00e8 controproducente trascorrere periodi di tempo lunghi sullo stesso compito. Modifica le vostre capacit\u00e0 di prendere decisioni, vi rende pi\u00f9 lenti e soggetti ad errori e pu\u00f2 ridurre la vostra adozione di comportamenti che vi mantengono in salute.<\/span><\/b><\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\">Se non potete fare veri e propri intervalli, almeno fermatevi un attimo: <span style=\"font-weight: 400;\">alzatevi o allontanatevi da quello che state facendo, distendete i muscoli, e fate qualche respiro profondo. Le evidenze suggeriscono che anche solo 30 secondi distogliendosi dal compito possono aiutare a ridurre l\u2019impatto cognitivo del lavoro ininterrotto.<\/span><\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\">Alternate le mansioni durante il giorno. <span style=\"font-weight: 400;\">Concentratevi su un singolo compito per un lasso di tempo predeterminato, e poi (a meno che siate \u201cnel pieno dell\u2019ispirazione\u201d) passate a qualcos\u2019altro. Da molti punti di vista, cognitivamente, cambiare fa bene quanto riposare.\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\">Incoraggiate gli altri a fare delle pause <span style=\"font-weight: 400;\">e strutturate servizi e mansioni che sono sotto il vostro controllo con modalit\u00e0 che permettono ai lavoratori di fare pause regolari. Nella societ\u00e0 moderna \u00e8 sempre pi\u00f9 importante creare proattivamente dei momenti di riposo all\u2019interno della giornata lavorativa.\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">[Tradotto da Claudia Meroni, Paola Scattola, Veronica Velasco]<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \u2018switched on\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2519,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[24,35],"tags":[],"class_list":["post-2510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-self-regulation","category-stress-and-coping"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"it","enabled_languages":["en","id","my","bg","zh","hr","cz","da","de","es","fr","gr","he","it","ja","kr","lv","lt","hu","nl","no","pl","pt","ro","ru","sk","sr","fi","sv","tr","uk"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"my":{"title":true,"content":true,"excerpt":false},"bg":{"title":true,"content":true,"excerpt":false},"zh":{"title":true,"content":true,"excerpt":false},"hr":{"title":false,"content":false,"excerpt":false},"cz":{"title":true,"content":true,"excerpt":false},"da":{"title":false,"content":false,"excerpt":false},"de":{"title":false,"content":false,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"gr":{"title":false,"content":false,"excerpt":false},"he":{"title":false,"content":false,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"kr":{"title":false,"content":false,"excerpt":false},"lv":{"title":true,"content":true,"excerpt":false},"lt":{"title":false,"content":false,"excerpt":false},"hu":{"title":false,"content":false,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"no":{"title":true,"content":true,"excerpt":false},"pl":{"title":true,"content":true,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"ro":{"title":false,"content":false,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"sk":{"title":true,"content":true,"excerpt":false},"sr":{"title":false,"content":false,"excerpt":false},"fi":{"title":true,"content":true,"excerpt":false},"sv":{"title":false,"content":false,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"uk":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"{:en}By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \u2018switched on\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the case for health professionals working in frontline healthcare services. In the healthcare context, working hours\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Julia Allan\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Practical Health Psychology - Tradurre la ricerca in pratica, un post sul blog alla volta\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0 - Practical Health Psychology\" \/>\n\t\t<meta property=\"og:description\" content=\"{:en}By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \u2018switched on\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the case for health professionals working in frontline healthcare services. In the healthcare context, working hours\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-08-04T07:20:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-04T14:01:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0 - Practical Health Psychology\" \/>\n\t\t<meta name=\"twitter:description\" content=\"{:en}By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \u2018switched on\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the case for health professionals working in frontline healthcare services. In the healthcare context, working hours\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#blogposting\",\"name\":\"Fare o fermarsi: l\\u2019importanza delle pause nella sanit\\u00e0 - Practical Health Psychology\",\"headline\":\"Fare o fermarsi: l\\u2019importanza delle pause nella sanit\\u00e0\",\"author\":{\"@id\":\"#molongui-disabled-link#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/fdf.jpg\",\"width\":5600,\"height\":3733},\"datePublished\":\"2022-08-04T07:20:38+00:00\",\"dateModified\":\"2025-11-04T14:01:36+00:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#webpage\"},\"articleSection\":\"Self-regulation, Stress and Coping\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/category\\\/self-regulation\\\/#listItem\",\"name\":\"Self-regulation\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/category\\\/self-regulation\\\/#listItem\",\"position\":2,\"name\":\"Self-regulation\",\"item\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/category\\\/self-regulation\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#listItem\",\"name\":\"Fare o fermarsi: l\\u2019importanza delle pause nella sanit\\u00e0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#listItem\",\"position\":3,\"name\":\"Fare o fermarsi: l\\u2019importanza delle pause nella sanit\\u00e0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/category\\\/self-regulation\\\/#listItem\",\"name\":\"Self-regulation\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/#organization\",\"name\":\"Practical Health Psychology\",\"description\":\"Tradurre la ricerca in pratica, un post sul blog alla volta\",\"url\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/\"},{\"@type\":\"Person\",\"@id\":\"#molongui-disabled-link#author\",\"url\":\"#molongui-disabled-link\",\"name\":\"Julia Allan\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Julia Allan\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#webpage\",\"url\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/\",\"name\":\"Fare o fermarsi: l\\u2019importanza delle pause nella sanit\\u00e0 - Practical Health Psychology\",\"description\":\"{:en}By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \\u2018switched on\\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the case for health professionals working in frontline healthcare services. In the healthcare context, working hours\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#breadcrumblist\"},\"author\":{\"@id\":\"#molongui-disabled-link#author\"},\"creator\":{\"@id\":\"#molongui-disabled-link#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/fdf.jpg\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#mainImage\",\"width\":5600,\"height\":3733},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/2022\\\/08\\\/make-or-break-the-importance-of-breaks-in-healthcare\\\/#mainImage\"},\"datePublished\":\"2022-08-04T07:20:38+00:00\",\"dateModified\":\"2025-11-04T14:01:36+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/\",\"name\":\"Practical Health Psychology\",\"description\":\"Tradurre la ricerca in pratica, un post sul blog alla volta\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/practicalhealthpsychology.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0 - Practical Health Psychology","description":"{:en}By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \u2018switched on\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the case for health professionals working in frontline healthcare services. In the healthcare context, working hours","canonical_url":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#blogposting","name":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0 - Practical Health Psychology","headline":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0","author":{"@id":"#molongui-disabled-link#author"},"publisher":{"@id":"https:\/\/practicalhealthpsychology.com\/it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/practicalhealthpsychology.com\/wp-content\/uploads\/2022\/08\/fdf.jpg","width":5600,"height":3733},"datePublished":"2022-08-04T07:20:38+00:00","dateModified":"2025-11-04T14:01:36+00:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#webpage"},"isPartOf":{"@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#webpage"},"articleSection":"Self-regulation, Stress and Coping"},{"@type":"BreadcrumbList","@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/practicalhealthpsychology.com\/it#listItem","position":1,"name":"Home","item":"https:\/\/practicalhealthpsychology.com\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/practicalhealthpsychology.com\/it\/category\/self-regulation\/#listItem","name":"Self-regulation"}},{"@type":"ListItem","@id":"https:\/\/practicalhealthpsychology.com\/it\/category\/self-regulation\/#listItem","position":2,"name":"Self-regulation","item":"https:\/\/practicalhealthpsychology.com\/it\/category\/self-regulation\/","nextItem":{"@type":"ListItem","@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#listItem","name":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/practicalhealthpsychology.com\/it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#listItem","position":3,"name":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0","previousItem":{"@type":"ListItem","@id":"https:\/\/practicalhealthpsychology.com\/it\/category\/self-regulation\/#listItem","name":"Self-regulation"}}]},{"@type":"Organization","@id":"https:\/\/practicalhealthpsychology.com\/it\/#organization","name":"Practical Health Psychology","description":"Tradurre la ricerca in pratica, un post sul blog alla volta","url":"https:\/\/practicalhealthpsychology.com\/it\/"},{"@type":"Person","@id":"#molongui-disabled-link#author","url":"#molongui-disabled-link","name":"Julia Allan","image":{"@type":"ImageObject","@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","width":96,"height":96,"caption":"Julia Allan"}},{"@type":"WebPage","@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#webpage","url":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/","name":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0 - Practical Health Psychology","description":"{:en}By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \u2018switched on\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the case for health professionals working in frontline healthcare services. In the healthcare context, working hours","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/practicalhealthpsychology.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#breadcrumblist"},"author":{"@id":"#molongui-disabled-link#author"},"creator":{"@id":"#molongui-disabled-link#author"},"image":{"@type":"ImageObject","url":"https:\/\/practicalhealthpsychology.com\/wp-content\/uploads\/2022\/08\/fdf.jpg","@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#mainImage","width":5600,"height":3733},"primaryImageOfPage":{"@id":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/#mainImage"},"datePublished":"2022-08-04T07:20:38+00:00","dateModified":"2025-11-04T14:01:36+00:00"},{"@type":"WebSite","@id":"https:\/\/practicalhealthpsychology.com\/it\/#website","url":"https:\/\/practicalhealthpsychology.com\/it\/","name":"Practical Health Psychology","description":"Tradurre la ricerca in pratica, un post sul blog alla volta","inLanguage":"it-IT","publisher":{"@id":"https:\/\/practicalhealthpsychology.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Practical Health Psychology - Tradurre la ricerca in pratica, un post sul blog alla volta","og:type":"article","og:title":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0 - Practical Health Psychology","og:description":"{:en}By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \u2018switched on\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the case for health professionals working in frontline healthcare services. In the healthcare context, working hours","og:url":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/","article:published_time":"2022-08-04T07:20:38+00:00","article:modified_time":"2025-11-04T14:01:36+00:00","twitter:card":"summary_large_image","twitter:title":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0 - Practical Health Psychology","twitter:description":"{:en}By Julia Allan, Aberdeen University, Scotland Modern life is hectic. We live in an increasingly \u2018switched on\u2019 digital world where periods of true respite from work are rare. Many people regularly work for lengthy periods and this is particularly the case for health professionals working in frontline healthcare services. In the healthcare context, working hours"},"aioseo_meta_data":{"post_id":"2510","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-07-02 13:52:14","updated":"2025-11-04 14:09:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/practicalhealthpsychology.com\/it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/practicalhealthpsychology.com\/it\/category\/self-regulation\/\" title=\"Self-regulation\">Self-regulation<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/practicalhealthpsychology.com\/it"},{"label":"Self-regulation","link":"https:\/\/practicalhealthpsychology.com\/it\/category\/self-regulation\/"},{"label":"Fare o fermarsi: l\u2019importanza delle pause nella sanit\u00e0","link":"https:\/\/practicalhealthpsychology.com\/it\/2022\/08\/make-or-break-the-importance-of-breaks-in-healthcare\/"}],"_links":{"self":[{"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/posts\/2510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/comments?post=2510"}],"version-history":[{"count":16,"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/posts\/2510\/revisions"}],"predecessor-version":[{"id":4559,"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/posts\/2510\/revisions\/4559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/media\/2519"}],"wp:attachment":[{"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/media?parent=2510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/categories?post=2510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/practicalhealthpsychology.com\/it\/wp-json\/wp\/v2\/tags?post=2510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}